{"id":802,"date":"2023-08-21T18:27:46","date_gmt":"2023-08-21T16:27:46","guid":{"rendered":"https:\/\/mhmlegal.org\/?p=802"},"modified":"2023-08-22T17:49:25","modified_gmt":"2023-08-22T15:49:25","slug":"acces-des-pme-aux-marches-publics","status":"publish","type":"post","link":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/","title":{"rendered":"Acc\u00e8s des PME aux march\u00e9s publics"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"802\" class=\"elementor elementor-802\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f937df9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f937df9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba94c40\" data-id=\"ba94c40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3b91e1 elementor-widget elementor-widget-text-editor\" data-id=\"f3b91e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9but janvier 2023, le conseil des ministres a donn\u00e9 son aval \u00e0 un projet de loi pr\u00e9liminaire qui vise \u00e0 am\u00e9liorer l&rsquo;acc\u00e8s des PME aux march\u00e9s publics. Cette initiative, propos\u00e9e par les ministres responsables des PME et de la Fonction publique, David Clarinval et Petra De Sutter, ainsi que par le Premier ministre Alexander De Croo, comprend plusieurs mesures en conformit\u00e9 avec un plan d&rsquo;action adopt\u00e9 en novembre 2021.<\/p><p>L&rsquo;une des dispositions principales de ce texte concerne la simplification des avances octroy\u00e9es dans le cadre des march\u00e9s publics. L&rsquo;octroi d&rsquo;une avance permettra aux adjudicataires d&rsquo;augmenter leurs liquidit\u00e9s en attendant le paiement des premi\u00e8res factures. Le principe \u00e9tabli pr\u00e9voit que l&rsquo;adjudicateur a le droit d&rsquo;accorder des avances, dont le montant ne peut exc\u00e9der 20 % du montant initial du march\u00e9, avec un plafond fix\u00e9 \u00e0 225 000 euros.<\/p><p>Par ailleurs, le projet de loi inclut \u00e9galement une disposition pour indemniser les entreprises non retenues, dans le cas o\u00f9 elles ont d\u00fb fournir des efforts intellectuels ou cr\u00e9atifs dans le cadre de la proc\u00e9dure pour soumettre une offre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>D\u00e9but janvier 2023, le conseil des ministres a donn\u00e9 son aval \u00e0 un projet de loi pr\u00e9liminaire qui vise \u00e0 am\u00e9liorer l&rsquo;acc\u00e8s des PME aux march\u00e9s publics. Cette initiative, propos\u00e9e par les ministres responsables des PME et de la Fonction publique, David Clarinval et Petra De Sutter, ainsi que par le Premier ministre Alexander De [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projet-de-loi","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acc\u00e8s des PME aux march\u00e9s publics - MHM Legal<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez avec MHM Legal le nouveau projet de loi qui facilitera l&#039;acc\u00e8s des PME aux march\u00e9s publics en Belgique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acc\u00e8s des PME aux march\u00e9s publics - MHM Legal\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez avec MHM Legal le nouveau projet de loi qui facilitera l&#039;acc\u00e8s des PME aux march\u00e9s publics en Belgique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/\" \/>\n<meta property=\"og:site_name\" content=\"MHM Legal\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-21T16:27:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-22T15:49:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/Actualite-MHM-Legal-Acces-des-pme-aux-marches-publics-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"EdouardLM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"EdouardLM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/\"},\"author\":{\"name\":\"EdouardLM\",\"@id\":\"https:\/\/mhmlegal.org\/#\/schema\/person\/cc48a050d72a61fd5de0efc4d9b65c32\"},\"headline\":\"Acc\u00e8s des PME aux march\u00e9s publics\",\"datePublished\":\"2023-08-21T16:27:46+00:00\",\"dateModified\":\"2023-08-22T15:49:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/\"},\"wordCount\":197,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/mhmlegal.org\/#\/schema\/person\/cc48a050d72a61fd5de0efc4d9b65c32\"},\"image\":{\"@id\":\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/Actualite-MHM-Legal-Acces-des-pme-aux-marches-publics-scaled.jpg\",\"articleSection\":[\"Projet de loi\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/\",\"url\":\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/\",\"name\":\"Acc\u00e8s des PME aux march\u00e9s publics - MHM Legal\",\"isPartOf\":{\"@id\":\"https:\/\/mhmlegal.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/Actualite-MHM-Legal-Acces-des-pme-aux-marches-publics-scaled.jpg\",\"datePublished\":\"2023-08-21T16:27:46+00:00\",\"dateModified\":\"2023-08-22T15:49:25+00:00\",\"description\":\"D\u00e9couvrez avec MHM Legal le nouveau projet de loi qui facilitera l'acc\u00e8s des PME aux march\u00e9s publics en Belgique.\",\"breadcrumb\":{\"@id\":\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#primaryimage\",\"url\":\"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/Actualite-MHM-Legal-Acces-des-pme-aux-marches-publics-scaled.jpg\",\"contentUrl\":\"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/Actualite-MHM-Legal-Acces-des-pme-aux-marches-publics-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"blog-MHM Legal-Acc\u00e8s des PME aux march\u00e9s publics\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/mhmlegal.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acc\u00e8s des PME aux march\u00e9s publics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mhmlegal.org\/#website\",\"url\":\"https:\/\/mhmlegal.org\/\",\"name\":\"MHM Legal\",\"description\":\"Consultant en march\u00e9s publics Belgique\",\"publisher\":{\"@id\":\"https:\/\/mhmlegal.org\/#\/schema\/person\/cc48a050d72a61fd5de0efc4d9b65c32\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mhmlegal.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/mhmlegal.org\/#\/schema\/person\/cc48a050d72a61fd5de0efc4d9b65c32\",\"name\":\"EdouardLM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mhmlegal.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/cropped-mhmlogo.png\",\"contentUrl\":\"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/cropped-mhmlogo.png\",\"width\":1363,\"height\":1319,\"caption\":\"EdouardLM\"},\"logo\":{\"@id\":\"https:\/\/mhmlegal.org\/#\/schema\/person\/image\/\"},\"sameAs\":[\"https:\/\/mhmlegal.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acc\u00e8s des PME aux march\u00e9s publics - MHM Legal","description":"D\u00e9couvrez avec MHM Legal le nouveau projet de loi qui facilitera l'acc\u00e8s des PME aux march\u00e9s publics en Belgique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/","og_locale":"fr_FR","og_type":"article","og_title":"Acc\u00e8s des PME aux march\u00e9s publics - MHM Legal","og_description":"D\u00e9couvrez avec MHM Legal le nouveau projet de loi qui facilitera l'acc\u00e8s des PME aux march\u00e9s publics en Belgique.","og_url":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/","og_site_name":"MHM Legal","article_published_time":"2023-08-21T16:27:46+00:00","article_modified_time":"2023-08-22T15:49:25+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/Actualite-MHM-Legal-Acces-des-pme-aux-marches-publics-scaled.jpg","type":"image\/jpeg"}],"author":"EdouardLM","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"EdouardLM","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#article","isPartOf":{"@id":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/"},"author":{"name":"EdouardLM","@id":"https:\/\/mhmlegal.org\/#\/schema\/person\/cc48a050d72a61fd5de0efc4d9b65c32"},"headline":"Acc\u00e8s des PME aux march\u00e9s publics","datePublished":"2023-08-21T16:27:46+00:00","dateModified":"2023-08-22T15:49:25+00:00","mainEntityOfPage":{"@id":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/"},"wordCount":197,"commentCount":0,"publisher":{"@id":"https:\/\/mhmlegal.org\/#\/schema\/person\/cc48a050d72a61fd5de0efc4d9b65c32"},"image":{"@id":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#primaryimage"},"thumbnailUrl":"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/Actualite-MHM-Legal-Acces-des-pme-aux-marches-publics-scaled.jpg","articleSection":["Projet de loi"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/","url":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/","name":"Acc\u00e8s des PME aux march\u00e9s publics - MHM Legal","isPartOf":{"@id":"https:\/\/mhmlegal.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#primaryimage"},"image":{"@id":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#primaryimage"},"thumbnailUrl":"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/Actualite-MHM-Legal-Acces-des-pme-aux-marches-publics-scaled.jpg","datePublished":"2023-08-21T16:27:46+00:00","dateModified":"2023-08-22T15:49:25+00:00","description":"D\u00e9couvrez avec MHM Legal le nouveau projet de loi qui facilitera l'acc\u00e8s des PME aux march\u00e9s publics en Belgique.","breadcrumb":{"@id":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#primaryimage","url":"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/Actualite-MHM-Legal-Acces-des-pme-aux-marches-publics-scaled.jpg","contentUrl":"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/Actualite-MHM-Legal-Acces-des-pme-aux-marches-publics-scaled.jpg","width":2560,"height":1707,"caption":"blog-MHM Legal-Acc\u00e8s des PME aux march\u00e9s publics"},{"@type":"BreadcrumbList","@id":"https:\/\/mhmlegal.org\/index.php\/2023\/08\/21\/acces-des-pme-aux-marches-publics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mhmlegal.org\/"},{"@type":"ListItem","position":2,"name":"Acc\u00e8s des PME aux march\u00e9s publics"}]},{"@type":"WebSite","@id":"https:\/\/mhmlegal.org\/#website","url":"https:\/\/mhmlegal.org\/","name":"MHM Legal","description":"Consultant en march\u00e9s publics Belgique","publisher":{"@id":"https:\/\/mhmlegal.org\/#\/schema\/person\/cc48a050d72a61fd5de0efc4d9b65c32"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mhmlegal.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/mhmlegal.org\/#\/schema\/person\/cc48a050d72a61fd5de0efc4d9b65c32","name":"EdouardLM","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mhmlegal.org\/#\/schema\/person\/image\/","url":"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/cropped-mhmlogo.png","contentUrl":"https:\/\/mhmlegal.org\/wp-content\/uploads\/2023\/08\/cropped-mhmlogo.png","width":1363,"height":1319,"caption":"EdouardLM"},"logo":{"@id":"https:\/\/mhmlegal.org\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/mhmlegal.org"]}]}},"_links":{"self":[{"href":"https:\/\/mhmlegal.org\/index.php\/wp-json\/wp\/v2\/posts\/802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mhmlegal.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mhmlegal.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mhmlegal.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mhmlegal.org\/index.php\/wp-json\/wp\/v2\/comments?post=802"}],"version-history":[{"count":12,"href":"https:\/\/mhmlegal.org\/index.php\/wp-json\/wp\/v2\/posts\/802\/revisions"}],"predecessor-version":[{"id":1005,"href":"https:\/\/mhmlegal.org\/index.php\/wp-json\/wp\/v2\/posts\/802\/revisions\/1005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mhmlegal.org\/index.php\/wp-json\/wp\/v2\/media\/804"}],"wp:attachment":[{"href":"https:\/\/mhmlegal.org\/index.php\/wp-json\/wp\/v2\/media?parent=802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mhmlegal.org\/index.php\/wp-json\/wp\/v2\/categories?post=802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mhmlegal.org\/index.php\/wp-json\/wp\/v2\/tags?post=802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}